{"id":1893,"date":"2019-07-24T21:23:38","date_gmt":"2019-07-25T00:23:38","guid":{"rendered":"http:\/\/espora13.com.br\/?p=1893"},"modified":"2019-07-24T21:36:17","modified_gmt":"2019-07-25T00:36:17","slug":"despedida-do-galo-feminino-no-brasileirao-feminino-sub-18-com-direito-a-goleada-e-golacos","status":"publish","type":"post","link":"https:\/\/espora13.com.br\/index.php\/2019\/07\/24\/despedida-do-galo-feminino-no-brasileirao-feminino-sub-18-com-direito-a-goleada-e-golacos\/","title":{"rendered":"Despedida do Galo Feminino no Brasileir\u00e3o Feminino Sub 18 com direito a goleada e gola\u00e7os!"},"content":{"rendered":"<ul>\n<li class=\"mceTemp\"><img loading=\"lazy\" class=\"wp-image-1894\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-17.49.20-300x263.jpeg\" alt=\"\" width=\"497\" height=\"435\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-17.49.20-300x263.jpeg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-17.49.20.jpeg 720w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/>\n<ul id=\"attachment_1894\" class=\"wp-caption alignnone\" style=\"width: 497px;\">Goleadoras de hoje: Ester, Andreza(2), Duda e Vit\u00f3ria<\/ul>\n<\/li>\n<\/ul>\n<p>Nesta quarta- feira, 24, \u00e0s 15:30 rolou o \u00faltimo jogo da primeira fase do Campeonato Brasileiro Feminino Sub 18.<br \/>\nAs advers\u00e1rias do Galo Feminino hoje foi o Ava\u00ed\/Kindermann que tomou uma goleada 5&#215;0 e deixou a posi\u00e7\u00e3o de 2\u00b0 lugar do grupo A para o Galo.<br \/>\nA etapa inicial come\u00e7ou e logo aos 3 minutos de partida a lateral Tete sofreu um p\u00eanalti. Quem foi para a cobran\u00e7a foi a Paloma Yasmin. A goleira Madu, do Ava\u00ed\/Kindermann, defendeu com a perna e a bola foi direto para o travess\u00e3o.<br \/>\nMesmo perdendo o p\u00eanalti as meninas alvinegras continuaram em cima, e aos 22 minutos a camisa dez, Duda, recebeu um cruzamento e mandou a bola para o fundo do gol. Abrindo o placar de 1&#215;0.<\/p>\n<figure id=\"attachment_1899\" aria-describedby=\"caption-attachment-1899\" style=\"width: 427px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\" wp-image-1899\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.08.47-300x169.jpeg\" alt=\"\" width=\"427\" height=\"241\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.08.47-300x169.jpeg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.08.47-768x432.jpeg 768w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.08.47-1024x576.jpeg 1024w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.08.47.jpeg 1280w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><figcaption id=\"caption-attachment-1899\" class=\"wp-caption-text\">Duda comemora o primeiro gol do jogo com o treinador<\/figcaption><\/figure>\n<p>Dezessete minutos depois, aos 39 minutos foi a vez da lateral Tete marcar com um gola\u00e7o, ap\u00f3s uma sa\u00edda de bola errada das catarinenses.<\/p>\n<figure id=\"attachment_1898\" aria-describedby=\"caption-attachment-1898\" style=\"width: 467px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\" wp-image-1898\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.19.27-300x169.jpeg\" alt=\"\" width=\"467\" height=\"263\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.19.27-300x169.jpeg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.19.27-768x432.jpeg 768w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.19.27-1024x576.jpeg 1024w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-21.19.27.jpeg 1280w\" sizes=\"(max-width: 467px) 100vw, 467px\" \/><figcaption id=\"caption-attachment-1898\" class=\"wp-caption-text\">Prepara\u00e7\u00e3o para a dancinha de comemora\u00e7\u00e3o do gol da Tete. Foto: MyCujoo<\/figcaption><\/figure>\n<p>O intervalo acaba e come\u00e7a o 2\u00b0 tempo. O Galo fez algumas substitui\u00e7\u00f5es e manteve o controle do jogo. E de novo, aos 3 minutos depois do apito inicial da 2\u00b0 etapa, a atacante Vit\u00f3ria, aniversariante do dia, faz outro gola\u00e7o.<\/p>\n<figure id=\"attachment_1895\" aria-describedby=\"caption-attachment-1895\" style=\"width: 479px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\" wp-image-1895\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-300x169.jpeg\" alt=\"\" width=\"479\" height=\"270\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-300x169.jpeg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-768x432.jpeg 768w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-1024x576.jpeg 1024w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52.jpeg 1280w\" sizes=\"(max-width: 479px) 100vw, 479px\" \/><figcaption id=\"caption-attachment-1895\" class=\"wp-caption-text\">Comemora\u00e7\u00e3o do terceiro gol, Vit\u00f3ria. Foto: MyCujoo<\/figcaption><\/figure>\n<p>As meninas n\u00e3o pararam por a\u00ed, j\u00e1 no finalzinho da partida Andressa p\u00f5e mais duas bolas na rede, com diferen\u00e7a de 1 minutos entre os gols, fechando o placar do jogo de 5&#215;0 para o Galo.<\/p>\n<figure id=\"attachment_1896\" aria-describedby=\"caption-attachment-1896\" style=\"width: 473px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\" wp-image-1896\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-2-300x169.jpeg\" alt=\"\" width=\"473\" height=\"266\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-2-300x169.jpeg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-2-768x432.jpeg 768w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-2-1024x576.jpeg 1024w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-24-at-20.30.52-2.jpeg 1280w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><figcaption id=\"caption-attachment-1896\" class=\"wp-caption-text\">Andreza comemorando seu segundo gol<\/figcaption><\/figure>\n<p>Do Grupo A, apenas as Sereias da Vila seguem para a segunda fase.<br \/>\nEsta foi a primeira edi\u00e7\u00e3o do Campeonato Brasileiro Sub 18. Nossas jogadoras est\u00e3o de parab\u00e9ns por terem jogado com ra\u00e7a, e honrado a camisa do glorioso Atl\u00e9tico Mineiro. Elas nos mostraram que a luta pela vaga nos pr\u00f3ximos campeonatos ser\u00e1 intensa, porque #ABASEVEMFORTE e muito capacitada para ganhar t\u00edtulos.<\/p>\n<p>A aniversariante do dia, Vit\u00f3ria Hellen, nos d\u00e1 uma palavrinha sobre a participa\u00e7\u00e3o no Campeonato.<\/p>\n<p>&#8220;A experi\u00eancia de participar do Campeonato Brasileiro Feminino Sub 18 foi incr\u00edvel, infelizmente n\u00e3o conseguimos ficar na primeira coloca\u00e7\u00e3o, mas sa\u00edmos muito orgulhosas pelo trabalho que fizemos aqui. Foi um campeonato muito desgastante, mas conseguimos lutar at\u00e9 o fim, quem nos conhece sabe que jogamos com ra\u00e7a at\u00e9 o final. Desta vez, a classifica\u00e7\u00e3o n\u00e3o veio, mas no pr\u00f3ximo ano viremos com mais ra\u00e7a para conseguirmos passar para a pr\u00f3xima fase. Quero agradecer o apoio de todos. Obrigado por nos apoiar sempre! &#8221; , disse Vit\u00f3ria.<\/p>\n<p>Esporada neles, Galo!!! Respeita as minas!!! Acredita nelas!!!<br \/>\nEspora 13, o portal de todas as modalidades do Galo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Goleadoras de hoje: Ester, Andreza(2), Duda e Vit\u00f3ria Nesta quarta- feira, 24, \u00e0s 15:30 rolou o \u00faltimo jogo da primeira<\/p>\n","protected":false},"author":6,"featured_media":1894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[96],"tags":[],"_links":{"self":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1893"}],"collection":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1893"}],"version-history":[{"count":3,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1893\/revisions"}],"predecessor-version":[{"id":1902,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1893\/revisions\/1902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/media\/1894"}],"wp:attachment":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}