{"id":3138,"date":"2019-12-14T11:42:50","date_gmt":"2019-12-14T14:42:50","guid":{"rendered":"http:\/\/espora13.com.br\/?p=3138"},"modified":"2019-12-14T13:43:19","modified_gmt":"2019-12-14T16:43:19","slug":"tecnico-sidney-lima-nao-e-mais-tecnico-do-galo-futebol-feminino-algumas-jogadoras-permanecem-para-2020","status":"publish","type":"post","link":"https:\/\/espora13.com.br\/index.php\/2019\/12\/14\/tecnico-sidney-lima-nao-e-mais-tecnico-do-galo-futebol-feminino-algumas-jogadoras-permanecem-para-2020\/","title":{"rendered":"Sidney Lima n\u00e3o \u00e9 mais t\u00e9cnico do Galo Futebol Feminino, algumas jogadoras permanecem para 2020"},"content":{"rendered":"<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"b6pvr-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"b6pvr-0-0\">\n<figure id=\"attachment_3140\" aria-describedby=\"caption-attachment-3140\" style=\"width: 741px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\" wp-image-3140\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/12\/12.jpg\" alt=\"\" width=\"741\" height=\"448\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/12\/12.jpg 1258w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/12\/12-300x181.jpg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/12\/12-768x464.jpg 768w, https:\/\/espora13.com.br\/wp-content\/uploads\/2019\/12\/12-1024x619.jpg 1024w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/><figcaption id=\"caption-attachment-3140\" class=\"wp-caption-text\">Imagem Reprodu\u00e7\u00e3o: TV Espora 13<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>O treinador Sidney Lima que comandou o Galo Futebol Feminino nesta temporada de 2019, n\u00e3o ficar\u00e1 para a pr\u00f3xima temporada.<\/p>\n<p>A coordenadora do Galo Futebol Feminino, Nina Abreu, confirmou a sa\u00edda do t\u00e9cnico na qual veio ao time alvinegro junto com as jogadoras do Prointer, na parceria feita com o Atl\u00e9tico.<\/p>\n<\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"7sfdg-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"7sfdg-0-0\"><span data-offset-key=\"7sfdg-0-0\">Com o Galo Futebol Feminino o treinador foi Campe\u00e3o da Copa BH 2019. J\u00e1 na s\u00e9rie A2 do Campeonato Brasileiro, o Atl\u00e9tico foi eliminado na fase de grupos com 1 empate e 4 derrotas, ficando na 5\u00b0 coloca\u00e7\u00e3o da competi\u00e7\u00e3o nacional.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"e7alg-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"e7alg-0-0\"><span data-offset-key=\"e7alg-0-0\">O time do Galo conseguiu vaga na edi\u00e7\u00e3o de 2020 gra\u00e7as ao Ranking da CBF, visto que no Campeonato Mineiro a equipe ficou em 3\u00b0 lugar, sendo eliminado nas semifinais pelo Am\u00e9rica.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"1fl2n-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1fl2n-0-0\"><span data-offset-key=\"1fl2n-0-0\">Em jogos oficiais o time comandado por Sidney teve 13 vit\u00f3rias, 3 empates e 6 derrotas, somando um aproveitamento de 63,6%.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"5kn8j-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"5kn8j-0-0\"><span data-offset-key=\"5kn8j-0-0\">Na\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=nRxg6lKEy0g\" target=\"_blank\" rel=\"noopener noreferrer\">Live realizada no canal TV Espora 13<\/a> nessa \u00faltima quinta-feira, 12, Nina Abreu disse que o planejamento do Galo Futebol Feminino est\u00e1 em andamento e confirmou alguns nomes para 2020 como, Duda que est\u00e1 servindo a Sele\u00e7\u00e3o Brasileira Sub-20, Isabella, Lorraine, Emily, Rayane, Amanda, Taluane e Isadora.\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"1t7ng-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1t7ng-0-0\"><span data-offset-key=\"1t7ng-0-0\">Nina ainda garantiu que o time de 2020 ser\u00e1 muito forte com atletas de alto n\u00edvel para conseguir o acesso para a s\u00e9rie A1 do Campeonato Brasileiro.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"1f7kn-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1f7kn-0-0\"><span data-offset-key=\"1f7kn-0-0\">Ela destaca que jogar na Cidade do Galo tem um custo bem menor. \u201c Com o dinheiro que desembolsamos para jogar no Est\u00e1dio das Alterosas, no Sesc Venda Nova, conseguimos pagar uma parte da folha salarial de todo m\u00eas do plantel alvinegro. Apenas os jogos do Campeonato Brasileiro A2, que n\u00e3o pode ser realizado no CT, deve ser realizado no Sesc Venda Nova.\u201d, afirma Nina.\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"9n39r-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"9n39r-0-0\"><span data-offset-key=\"9n39r-0-0\">Na <a href=\"https:\/\/www.youtube.com\/watch?v=nRxg6lKEy0g\" target=\"_blank\" rel=\"noopener noreferrer\">Live no TV Espora 13<\/a>\u00a0a coordenadora tamb\u00e9m contou a hist\u00f3ria da Amanda Moura, que ainda tem dificuldades para oficializar com Galo e por isso, n\u00e3o jogou a semifinal do campeonato estadual, contra o Am\u00e9rica.\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"7vlck-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"7vlck-0-0\"><span data-offset-key=\"7vlck-0-0\"><br \/>\nEstamos na torcida para que no ano de 2020 o Galo Futebol Feminino venha com tudo rumo \u00e0 \u00a0grandes conquistas e que a Massa abrace realmente essa modalidade, que \u00e9 muito importante para a institui\u00e7\u00e3o Clube Atl\u00e9tico Mineiro.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"5qq7i-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"5qq7i-0-0\"><span data-offset-key=\"5qq7i-0-0\">Sucesso a todos que est\u00e3o deixando o Galo e um muito obrigado por terem honrado o manto sagrado alvinegro!<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"fdl6q-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"fdl6q-0-0\"><span data-offset-key=\"fdl6q-0-0\">Muito obrigado tamb\u00e9m a voc\u00ea leitor por ter acompanhado o nosso trabalho neste ano de 2019, o Espora 13 \u00e9 o portal de todas modalidades do Galo e fazemos isso para voc\u00ea torcedor atleticano.<\/span><\/div>\n<div data-offset-key=\"fdl6q-0-0\">Siga o <a href=\"https:\/\/twitter.com\/Espora13\" target=\"_blank\" rel=\"noopener noreferrer\">Espora 13<\/a> nas redes sociais. Desejamos a voc\u00eas um feliz Natal, um prospero Ano Novo!<\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"6v6gl-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"6v6gl-0-0\"><span data-offset-key=\"6v6gl-0-0\">Voltaremos com tudo em 2020 cobrindo todas modalidades do Galo.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"6rsip-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"6rsip-0-0\"><span data-offset-key=\"6rsip-0-0\">Estamos juntos sempre!<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ft1q6\" data-offset-key=\"27os2-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"27os2-0-0\"><span data-offset-key=\"27os2-0-0\">Esporada neles Galo!<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O treinador Sidney Lima que comandou o Galo Futebol Feminino nesta temporada de 2019, n\u00e3o ficar\u00e1 para a pr\u00f3xima<\/p>\n","protected":false},"author":8,"featured_media":3140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[96],"tags":[106],"_links":{"self":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3138"}],"collection":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3138"}],"version-history":[{"count":5,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3138\/revisions"}],"predecessor-version":[{"id":3145,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3138\/revisions\/3145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/media\/3140"}],"wp:attachment":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}