{"id":4509,"date":"2021-01-25T22:25:51","date_gmt":"2021-01-26T01:25:51","guid":{"rendered":"http:\/\/espora13.com.br\/?p=4509"},"modified":"2021-01-25T22:25:51","modified_gmt":"2021-01-26T01:25:51","slug":"missao-4-10-apos-vexame-galo-enfrenta-o-santos-no-mineirao-para-se-firmar-entre-os-primeiros-do-brasileirao","status":"publish","type":"post","link":"https:\/\/espora13.com.br\/index.php\/2021\/01\/25\/missao-4-10-apos-vexame-galo-enfrenta-o-santos-no-mineirao-para-se-firmar-entre-os-primeiros-do-brasileirao\/","title":{"rendered":"Miss\u00e3o 4\/10: Ap\u00f3s vexame, Galo enfrenta o Santos no Mineir\u00e3o para se firmar entre os primeiros do Brasileir\u00e3o"},"content":{"rendered":"<figure id=\"attachment_4510\" aria-describedby=\"caption-attachment-4510\" style=\"width: 2047px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-4510 size-full\" src=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k.jpg\" alt=\"Espora 13 - Atl\u00e9tico - Galo - Atl\u00e9tico MG- GALO- SANTOS- GALO X SANTOS\" width=\"2047\" height=\"1365\" srcset=\"https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k.jpg 2047w, https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k-300x200.jpg 300w, https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k-1024x683.jpg 1024w, https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k-768x512.jpg 768w, https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k-1536x1024.jpg 1536w, https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k-177x118.jpg 177w, https:\/\/espora13.com.br\/wp-content\/uploads\/2021\/01\/50874588667_4ad7e40e9b_k-272x182.jpg 272w\" sizes=\"(max-width: 2047px) 100vw, 2047px\" \/><figcaption id=\"caption-attachment-4510\" class=\"wp-caption-text\">Fotos: Pedro Souza \/ Atl\u00e9tico<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>\u00c9 dia de Galo!!<\/p>\n<p>Dia de jogo decisivo!<\/p>\n<p>Dia de encurtar a dist\u00e2ncia pro l\u00edder!<\/p>\n<p>Mais uma batalha em busca de um sonho!!<\/p>\n<p>A semana come\u00e7ou, e j\u00e1 temos Galo em campo novamente, ap\u00f3s o vexame na \u00faltima rodada com uma amarga derrota para o Vasco, O Galo tenta dar uma resposta em campo \u00e0 sua apaixonada torcida, nesta quarta-feira,26, \u00e0s 20:00 hrs (Bras\u00edlia), diante do Santos, com o time totalmente reserva, j\u00e1 que o time do t\u00e9cnico Cuca est\u00e1 envolvido nas finais da Copa Libertadores da Am\u00e9rica.<\/p>\n<p>O Santos est\u00e1 de bem com vida, mesmo vivendo uma temporada dif\u00edcil, com a parte financeira e puni\u00e7\u00f5es a todo tempo vindo \u00e0 tona, o time de Cuca se superou e confiando nos talentos da base x experientes, o clube peixeiro disputar\u00e1 a final da Libertadores com o sonho de conquistar a Am\u00e9rica novamente. Cuca poupou todos seus titulares, e vir\u00e1 com um time totalmente reserva para o Mineir\u00e3o, um time repleto de jovens jogadores, que prometem correria e muita velocidade para cima do atual quarto colocado do brasileir\u00e3o.<\/p>\n<p>J\u00e1 o Galo volta \u00e0 campo, ap\u00f3s vexame no \u00faltimo domingo, uma partida que deixou a torcida de mal com o time, devido time abaixo da cr\u00edtica e v\u00e1rios atletas jogando com um clima longe de um jogo decisivo, com a derrota, o sonho do t\u00edtulo brasileiro esfriou, e a torcida tem cobrado melhores apresenta\u00e7\u00f5es do time comandado por Jorge Sampaoli. O treinador alvinegro promete uma resposta nas pr\u00f3ximas rodadas, e tenta manter vivo o sonho de conquista dentro do elenco, contando com algumas altera\u00e7\u00f5es devemos ver o time com a base das ultimas apresenta\u00e7\u00f5es, por\u00e9m, o t\u00e9cnico cobrou uma atitude melhor, atitude de time que briga pelas primeiras coloca\u00e7\u00f5es no Campeonato. Para corrigir os problemas defensivos, o zagueiro Rever deve voltar ao time, assim como Jair deve ser o primeiro volante ao lado de Nathan ou Alan Franco que brigam por uma posi\u00e7\u00e3o no meio campo alvinegro. Vargas e Keno vivem press\u00e3o por gols, e andam pecando no momento de defini\u00e7\u00e3o, dentro da Cidade do Galo nem se cogita um resultado diferente de vit\u00f3ria diante de um Santos totalmente reserva.<\/p>\n<p>O Galo fez uma partida para esquecer, uma das piores apresenta\u00e7\u00f5es do time logo em um momento crucial do campeonato. Aparentemente, o time n\u00e3o sabe lidar com a press\u00e3o de ter que vencer, com isso sempre perde pontos quando poderia chegar pr\u00f3ximo a ponta da tabela. O resultado frustrou a torcida, que v\u00ea a ta\u00e7a cada vez mais distante, uma vit\u00f3ria contra o Santos \u00e9 tratada com obriga\u00e7\u00e3o, qualquer resultado diferente disso seria um desastre. O que se espere \u00e9 ATITUDE, que os atletas entendam o momento de decis\u00e3o das ultimas rodadas, e honrem esta camisa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>TENHAM ATITUDE DE TIME CAMPE\u00c3O!!!!<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>Vamos pra cima deles Galo!!<\/p>\n<p>Contra o vento novamente!<\/p>\n<p>Vamos Galo!<\/p>\n<p>Aqui \u00e9 Galo, Sempre!<\/p>\n<p>Esporada Neles Galo!!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FICHA T\u00c9CNICA DA PARTIDA<\/strong><\/p>\n<p>ATLETICO X SANTOS<br \/>\n\u200bEst\u00e1dio: Mineir\u00e3o<\/p>\n<p>Data e hora: 26 de janeiro de 2021, \u00e0s 20:00 (de Bras\u00edlia)<\/p>\n<p>Motivo: 28\u00aa rodada Brasileir\u00e3o (Jogo atrasado)<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>PROV\u00c1VEIS ESCALA\u00c7\u00d5ES: <\/u><\/strong><\/p>\n<p><strong><u>Atl\u00e9tico:<\/u><\/strong><\/p>\n<p>O prov\u00e1vel time escalado:<\/p>\n<p>Everson, Guga, R\u00e9ver, Junior Alonso, Guilherme Arana, Jair, Nathan, Hyoran, Savarino, Keno e Eduardo Vargas (Eduardo Sasha). T\u00e9cnico: Jorge Sampaoli<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Santos<u>:<\/u><\/strong><\/p>\n<p>O prov\u00e1vel time escalado:<\/p>\n<p>John, Madson, La\u00e9rcio, Alex, Wagner Leonardo, Vin\u00edcius Balieiro, Guilherme Nunes, Lucas Louren\u00e7o, Jean Mota, Arthur Gomes e Bruno Marques. T\u00e9cnico: Cuca.<\/p>\n<p>&nbsp;<\/p>\n<p>Ap\u00f3s o jog\u00e3o fique ligado no Canal do Youtube\u00a0<a href=\"https:\/\/www.youtube.com\/tvespora13\">TV Espora 13<\/a>, com o P\u00f3s-jogo AO VIVO com\u00a0<a href=\"https:\/\/www.instagram.com\/leoaj13\/\">L\u00e9o AJ<\/a>\u00a0\u00e0s 22h30<\/p>\n<p>Inscreva-se no canal!<\/p>\n<p>Para mais informa\u00e7\u00f5es do Atl\u00e9tico, siga o Espora 13 nas redes sociais:<\/p>\n<p><a href=\"https:\/\/twitter.com\/Espora13\">Clica e Siga no Twitter<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/espora13oficial\">Clica e Siga no\u00a0Facebook<\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/espora13\/\">Clica e Siga no Instagram<\/a><\/p>\n<p><a href=\"https:\/\/www.twitch.tv\/espora13\">Clica e Siga na Twitch<\/a><\/p>\n<p><a href=\"https:\/\/open.spotify.com\/user\/5ljo01qd7to5rzprw8tpdkwg6?si=IJ9LRCfKTQGzLaiI_pSo4w\">Clica e Siga no Spotify<\/a><\/p>\n<p><a href=\"https:\/\/vm.tiktok.com\/ZMJWsH9ua\/\">Clica e Siga no Tik Tok<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/tvespora13\">Inscreva-se no canal do youtube TV Espora 13<\/a><\/p>\n<p>Esporada neles Galooooooooooooo!!!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00c9 dia de Galo!! Dia de jogo decisivo! Dia de encurtar a dist\u00e2ncia pro l\u00edder! Mais uma batalha em<\/p>\n","protected":false},"author":25,"featured_media":4510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[73],"tags":[],"_links":{"self":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4509"}],"collection":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4509"}],"version-history":[{"count":1,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4509\/revisions"}],"predecessor-version":[{"id":4511,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4509\/revisions\/4511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/media\/4510"}],"wp:attachment":[{"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espora13.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}